{"id":3270,"date":"2016-10-10T07:30:10","date_gmt":"2016-10-10T07:30:10","guid":{"rendered":"http:\/\/blog.snapfish.de\/?p=3270\/?p=3270"},"modified":"2021-08-24T17:26:02","modified_gmt":"2021-08-24T17:26:02","slug":"blogger-tipps-erstellen-einer-wand-voller-leinwaende","status":"publish","type":"post","link":"https:\/\/www.snapfish.de\/magazin\/blogger-tipps-erstellen-einer-wand-voller-leinwaende\/","title":{"rendered":"Blogger Tipps: Erstellen einer Wand voller Leinw\u00e4nde"},"content":{"rendered":"<p><span style=\"color: #808080;\"><span style=\"font-weight: 400;\">Von Petra von <\/span><span style=\"font-weight: 400;\">A Mum Reviews<\/span><\/span><\/p>\n<p><span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3153 size-full\" src=\"https:\/\/www.snapfish.de\/magazin\/wp-content\/uploads\/2016\/08\/image-4.jpg\" alt=\"image-4\" width=\"720\" height=\"460\" srcset=\"https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-4.jpg 720w, https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-4-300x192.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Wir haben gerade begonnen eine Wand in unserem Haus neu zu gestalten mit einer Mischung aus Fotos, Bildern und Illustrationen. \u00a0Diese zeigen meine Familie und meine Leidenschaften. Es ist eine Wand, welche nach und nach wachsen wird mit neuen Fotos und Kunstwerken.<\/span><\/p>\n<p><span style=\"color: #808080;\"><!--more--><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">F\u00fcr den Start \u00a0haben wir 3 <a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\">Leinw\u00e4nde bestellt<\/a> &#8211; in den Gr\u00f6\u00dfen 30&#215;45 cm bzw. 40&#215;60 cm. Du kannst mit jeder Gr\u00f6\u00dfe starten so lange noch f\u00fcr weitere Leinw\u00e4nde Platz bleibt an der Wand. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Nach wenigen Tagen erhielt ich die Lieferung von <a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/home?CID=de|mic|post|blogde|sep16|web|snapfishde|site\">Snapfish<\/a>. Sie waren einzeln verpackt und gut gesch\u00fctzt. <\/span><\/p>\n<p><span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3150 size-full\" src=\"https:\/\/blog.snapfish.co.uk\/wp-content\/uploads\/2016\/08\/image-1.jpg\" alt=\"image-1\" width=\"720\" height=\"460\" srcset=\"https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-1.jpg 720w, https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-1-300x192.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Die Fotos, welche wir ausgew\u00e4hlt haben, sind meine Lieblingsbilder. Die Bilder zeigen sehr verschiedene Momente, aber passen trotzdem zusammen. Ich denke, es ist wichtig, einen Mix von unterschiedlichen Bildern und Stilen zu haben, gleichzeitig aber etwas Verbindendes. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Wir haben eine Wand in unserem Treppenhaus ausgesucht, da es ein sch\u00f6ner, aber ungenutzer Bereich in unserem Haus ist. Er war ziemlich langweilig mit nur wei\u00dfer Tapete. Wei\u00dfe W\u00e4nde sind perfekt, um die Leinw\u00e4nde richtig zur Geltung zu bringen. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Ich hatte eine Idee, wie es aussehen sollte. Um aber genau zu planen, habe ich eine Skizze am Computer erstellt. So konnte ich mit mehreren Optionen spielen und die Leinw\u00e4nde unterschiedlich anordnen. Am Computer hat man den Vorteil, direkt die Bilder einzuf\u00fcgen und hin-und her zu bewegen. Du kannst aber nat\u00fcrlich auch eine Skizze per Hand auf Papier anfertigen.<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Nach mehreren Ideen und der Lieferung der Leinw\u00e4nde, haben wir uns schlie\u00dflich f\u00fcr diesen Plan entschieden:<\/span><\/p>\n<p><span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3151 size-full\" src=\"https:\/\/www.snapfish.de\/magazin\/wp-content\/uploads\/2016\/08\/image-2.jpg\" alt=\"image-2\" width=\"720\" height=\"460\" srcset=\"https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-2.jpg 720w, https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-2-300x192.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Die linke Seite zeigt wie wir unsere drei neuen Leinw\u00e4nde anordnen m\u00f6chten und die rechte Seite zeigt, wie wir es zuk\u00fcnftig erweitern k\u00f6nnten.<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Wir haben die Bilder mittig \u00fcber eine Kommode angeordnet. Wenn wir das Ganze direkt an der Treppe gestaltet h\u00e4tten, dann w\u00e4re es das Beste gewesen, oben zu beginnen und in Richtung unten auszurichten. Bei einer freien Wand sollte man immer in der Mitte starten, um einen ausgewogenen Anblick zu haben. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Alles, was du ben\u00f6tigst:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400; color: #808080;\">N\u00e4gel<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400; color: #808080;\">Hammer<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400; color: #808080;\">Klebeband<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400; color: #808080;\">Wasserwaage<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400; color: #808080;\">Saubere H\u00e4nde! Leinw\u00e4nde sind empfindlich und du m\u00f6chtest sicher keine st\u00f6renden Fingerabdr\u00fccke auf deinen neuen Fotos an der Wand haben. \u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400; color: #808080;\">Ich habe meinen Mann gebeten mir zu helfen. Es geht zu zweit besser. Man kann sicher stellen, dass die Bilder an den richtigen Platz kommen und gerade h\u00e4ngen.<\/span><\/p>\n<p><span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3152 size-full\" src=\"https:\/\/blog.snapfish.co.uk\/wp-content\/uploads\/2016\/08\/image-3.jpg\" alt=\"image-3\" width=\"720\" height=\"460\" srcset=\"https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-3.jpg 720w, https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-3-300x192.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Auch wenn wir einen festen Plan hatten, so war dieser doch nicht in Stein gemei\u00dfelt. Wir haben geschaut, wie es genau an der Wand wirkt und noch leichte Korrekturen vorgenommen. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Wir haben einen Nagel pro Leinwand verwendet. Dies war am einfachsten. Wenn du m\u00f6chtest, kannst du auch zwei N\u00e4gel verwenden, dabei muss aber genauer gemessen werden und es ist mehr Aufwand, wenn die Leinw\u00e4nde eventuell neu angeordnet werden sollen. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Es ist eine gute Idee, die Abst\u00e4nde zwischen den Leinw\u00e4nden auszumessen, aber manchmal hilft auch Augenma\u00df. F\u00fcr eine ordentliche Optik empfiehlt es sich, einige Bilder auf diesselbe Kante auszurichten. <\/span><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Hier ist das Ergebnis &#8211; der Start von unserer neu gestalteten Wand:<\/span><\/p>\n<p><a href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #808080;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3153 size-full aligncenter\" src=\"https:\/\/www.snapfish.de\/magazin\/wp-content\/uploads\/2016\/08\/image-4.jpg\" alt=\"\" width=\"720\" height=\"460\" srcset=\"https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-4.jpg 720w, https:\/\/blog.snapfish.de\/wp-content\/uploads\/2016\/08\/image-4-300x192.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/p>\n<p><span style=\"font-weight: 400; color: #808080;\">Wir sind sehr zufrieden mit unserem Ergebnis und finden, es sieht wirklich toll aus. Es sieht gut aus, wie es ist, aber wir k\u00f6nnen bereits erahnen, wie es mit weiteren Leinw\u00e4nden aussehen wird. \u00a0Wir werden es noch weiter ausbauen und weitere Lieblingsbilder hinzuf\u00fcgen!<\/span><\/p>\n<p><span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"https:\/\/www.snapfish.de\/wanddekoration?CID=de|mic|post|blogde|sep16|web|snapfishde|wal\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Entdecke unsere verschiedenen Leinw\u00e4nde!<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Petra von A Mum Reviews Wir haben gerade begonnen eine Wand in unserem Haus neu zu gestalten mit einer Mischung aus Fotos, Bildern und Illustrationen. \u00a0Diese zeigen meine Familie und meine Leidenschaften. Es ist eine Wand, welche nach und nach wachsen wird mit neuen Fotos und Kunstwerken.<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[649,624],"tags":[],"class_list":["post-3270","post","type-post","status-publish","format-standard","hentry","category-praktisches","category-wanddekoration-de"],"_links":{"self":[{"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/posts\/3270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/comments?post=3270"}],"version-history":[{"count":5,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/posts\/3270\/revisions"}],"predecessor-version":[{"id":7775,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/posts\/3270\/revisions\/7775"}],"wp:attachment":[{"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/media?parent=3270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/categories?post=3270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snapfish.de\/magazin\/wp-json\/wp\/v2\/tags?post=3270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}